{"id":1032750,"date":"2026-07-13T22:47:35","date_gmt":"2026-07-13T20:47:35","guid":{"rendered":"https:\/\/www.moensmeubelen.be\/product\/3330-lella-franco-ferri-fr_be\/"},"modified":"2026-07-13T22:53:31","modified_gmt":"2026-07-13T20:53:31","slug":"3330-lella-franco-ferri-fr_be","status":"publish","type":"product","link":"https:\/\/www.moensmeubelen.be\/fr\/produit\/3330-lella-franco-ferri-fr_be\/","title":{"rendered":"3330 &#8211; Salon d&#8217;angle Lella"},"content":{"rendered":"<p>Ce Salon d&#8217;angle Lella (Franco Ferri) 1 place large sans accoudoirs (dossier mobile), 1 place large accoudoir G et meridienne large accoudoir D (accoudoir et dossier mobiles, L143 P194). Tissu Cat 70 Boston 015 Forest, confort soft foam, pieds metal. La version presentee est livree a partir de 3.880 euros. D&#8217;autres versions, tissus\/cuirs et configurations sont possibles &#8211; renseignez-vous aupres de nos vendeurs.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Salon d&#8217;angle Lella. 1 place large sans accoudoirs (dossier mobile), 1 place large accoudoir G et meridienne large accoudoir D (accoudoir et dossier mobiles, L143 P194). Tissu Cat 70 Boston 015 Forest, confort soft foam, pieds metal.<\/p>\n","protected":false},"featured_media":1032751,"comment_status":"open","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"product_brand":[],"product_cat":[5647],"product_tag":[],"class_list":["post-1032750","product","type-product","status-publish","has-post-thumbnail","product_cat-zetels_l2_fr_BE","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/product\/1032750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/comments?post=1032750"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/media\/1032751"}],"wp:attachment":[{"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/media?parent=1032750"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/product_brand?post=1032750"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/product_cat?post=1032750"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/product_tag?post=1032750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}