{"id":725281,"date":"2026-06-28T00:00:00","date_gmt":"2026-06-28T00:00:00","guid":{"rendered":""},"modified":"2026-08-11T11:41:39","modified_gmt":"2026-08-11T09:41:39","slug":"47563KOP-fr_BE","status":"publish","type":"product","link":"https:\/\/www.moensmeubelen.be\/fr\/produit\/47563KOP-fr_BE\/","title":{"rendered":"Timeless &#8211; Evie coussin 45x45cm &#8211; Cuivre"},"content":{"rendered":"<p>Un coussin doux a l\\&#8217;air encore plus confortable apr\u00e8s une longue journ\u00e9e. Evie vous aide \u00e0 prendre du temps pour vous, pour vous d\u00e9tendre et vous relaxer. Evie est un coussin doux recouvert de fausse fourrure \u00e0 l\\&#8217;avant et \u00e0 l\\&#8217;arri\u00e8re. Ce tissu doux vous invite \u00e0 vous installer confortablement avec ce coussin sous votre t\u00eate. Evie est un coussin de couleur cuivr\u00e9e, mais existe en d\\&#8217;autres coloris chaleureux. Quelle couleur de coussin choisirez-vous pour vous d\u00e9tendre confortablement\u00a0?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Timeless &#8211; Evie coussin 45x45cm &#8211; Cuivre<\/p>\n","protected":false},"featured_media":1001995,"comment_status":"open","ping_status":"open","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"product_brand":[],"product_cat":[24113],"product_tag":[],"class_list":["post-725281","product","type-product","status-publish","has-post-thumbnail","product_cat-Kussens_fr_BE","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/product\/725281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/comments?post=725281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/media\/1001995"}],"wp:attachment":[{"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/media?parent=725281"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/product_brand?post=725281"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/product_cat?post=725281"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/product_tag?post=725281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}