{"id":796587,"date":"2026-06-28T00:00:00","date_gmt":"2026-06-28T00:00:00","guid":{"rendered":""},"modified":"2026-06-28T13:48:27","modified_gmt":"2026-06-28T11:48:27","slug":"54723NAT-fr_BE","status":"publish","type":"product","link":"https:\/\/www.moensmeubelen.be\/fr\/produit\/54723NAT-fr_BE\/","title":{"rendered":"Avalox, table de bar ovale 210 x 110 cm &#8211; couleur natural &#8211; 4 pied"},"content":{"rendered":"<p>Cette table de bar moderne de la collection Avalox attire tous les regards. La table de bar mesure 210&#215;110 cm et se distingue par son plateau ovale. Dans la collection Avalox, vous trouverez diff\u00e9rents types et tailles de tables de bar. Les pieds en m\u00e9tal noir conf\u00e8rent \u00e0 la table un caract\u00e8re robuste. Vous pouvez choisir parmi 2 variantes diff\u00e9rentes. Le plateau de table est disponible dans les couleurs bois flott\u00e9 ou ch\u00eane naturel vintage. Laquelle est votre pr\u00e9f\u00e9r\u00e9e ?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avalox, table de bar ovale 210 x 110 cm &#8211; couleur natural &#8211; 4 pied<\/p>\n","protected":false},"featured_media":992775,"comment_status":"open","ping_status":"open","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"product_brand":[],"product_cat":[1314],"product_tag":[],"class_list":["post-796587","product","type-product","status-publish","has-post-thumbnail","product_cat-bartafels_fr_BE","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/product\/796587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/comments?post=796587"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/media\/992775"}],"wp:attachment":[{"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/media?parent=796587"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/product_brand?post=796587"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/product_cat?post=796587"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/product_tag?post=796587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}