{"id":829088,"date":"2026-06-28T00:00:00","date_gmt":"2026-06-28T00:00:00","guid":{"rendered":"https:\/\/www.moensmeubelen.be\/product\/50264kop-fr_be\/"},"modified":"2026-06-28T21:41:52","modified_gmt":"2026-06-28T19:41:52","slug":"50264KOP-fr_BE","status":"publish","type":"product","link":"https:\/\/www.moensmeubelen.be\/fr\/produit\/50264KOP-fr_BE\/","title":{"rendered":"Timeless Arawood tapis 220x300cm &#8211; cuivre"},"content":{"rendered":"<p>Le tapis Arawood de la collection Timeless de <strong>COCO<\/strong>maison est un v\u00e9ritable accroche-regard et est fabriqu\u00e9 en polyester. Ce tapis a une dimension de 220 x 300 cm et une forme organique de galet. Il est disponible en trois couleurs diff\u00e9rentes, dont cette variante cuivre. Ce tapis ajoute une touche de beaut\u00e9 naturelle \u00e0 n\\&#8217;importe quel espace et offre \u00e0 la fois style et confort. Le mat\u00e9riau polyester de haute qualit\u00e9 garantit que le tapis est facile \u00e0 entretenir et durable. Le tapis Arawood de la collection Timeless de <strong>COCO<\/strong>maison est le choix id\u00e9al pour ceux qui recherchent une combinaison d\\&#8217;\u00e9l\u00e9gance, de confort et de fonctionnalit\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Timeless Arawood tapis 220x300cm &#8211; cuivre<\/p>\n","protected":false},"featured_media":1004107,"comment_status":"open","ping_status":"open","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"product_brand":[],"product_cat":[1777],"product_tag":[],"class_list":["post-829088","product","type-product","status-publish","has-post-thumbnail","product_cat-tapijten_fr_BE","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/product\/829088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/comments?post=829088"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/media\/1004107"}],"wp:attachment":[{"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/media?parent=829088"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/product_brand?post=829088"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/product_cat?post=829088"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/product_tag?post=829088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}