{"id":885684,"date":"2026-02-07T18:19:19","date_gmt":"2026-02-07T17:19:19","guid":{"rendered":"https:\/\/www.moensmeubelen.be\/product\/revor24-fr_be\/"},"modified":"2026-08-30T09:04:27","modified_gmt":"2026-08-30T07:04:27","slug":"revor24-fr_be","status":"publish","type":"product","link":"https:\/\/www.moensmeubelen.be\/fr\/produit\/revor24-fr_be\/","title":{"rendered":"Scandi Surmatelas Nature"},"content":{"rendered":"<p>Offrez-vous un confort ultime avec notre Scandi Surmatelas Nature. La housse amovible en ecodown offre une sensation duveteuse agr\u00e9able pour une exp\u00e9rience de sommeil luxueuse. Le noyau en latex naturel est tr\u00e8s \u00e9lastique et offre un soutien parfait pour votre corps dans chaque position de sommeil. La housse ecodown est nettoyable chimiquement, assurant un entretien facile et une fra\u00eecheur durable. Am\u00e9liorez votre sommeil avec le Scandi Surmatelas Nature, qui combine des mat\u00e9riaux respectueux de l&#8217;environnement avec un confort et un soutien exceptionnels.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Offrez-vous un confort ultime avec notre Scandi Surmatelas Nature. La housse amovible en ecodown offre une sensation duveteuse agr\u00e9able pour une exp\u00e9rience de sommeil luxueuse. Le noyau en latex naturel est tr\u00e8s \u00e9lastique et offre un soutien parfait pour votre corps dans chaque position de sommeil. La housse ecodown est nettoyable chimiquement, assurant un entretien facile et une fra\u00eecheur durable. Am\u00e9liorez votre sommeil avec le Scandi Surmatelas Nature, qui combine des mat\u00e9riaux respectueux de l&#8217;environnement avec un confort et un soutien exceptionnels.<\/p>\n","protected":false},"featured_media":885686,"comment_status":"open","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"product_brand":[],"product_cat":[24410],"product_tag":[],"class_list":["post-885684","product","type-product","status-publish","has-post-thumbnail","product_cat-toppers_fr_be-matrassen_fr_BE","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/product\/885684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/comments?post=885684"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/media\/885686"}],"wp:attachment":[{"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/media?parent=885684"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/product_brand?post=885684"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/product_cat?post=885684"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.moensmeubelen.be\/fr\/wp-json\/wp\/v2\/product_tag?post=885684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}